{"id":8280,"date":"2024-01-19T14:16:39","date_gmt":"2024-01-19T13:16:39","guid":{"rendered":"https:\/\/dise.org.pl\/en\/?page_id=8280"},"modified":"2024-01-19T14:21:09","modified_gmt":"2024-01-19T13:21:09","slug":"inla-contact","status":"publish","type":"page","link":"https:\/\/dise.org.pl\/en\/inla-contact\/","title":{"rendered":"INLA CONTACT"},"content":{"rendered":"<p>[vc_row bg_type=&#8221;bg_color&#8221; bg_override=&#8221;ex-full&#8221; type=&#8221;vc_default&#8221; margin_bottom=&#8221;60&#8243; css=&#8221;.vc_custom_1521105454027{padding-top: 60px !important;padding-bottom: 60px !important;background-color: #0e182b !important;}&#8221; el_id=&#8221;kontaktwebsite&#8221; bg_color_value=&#8221;#1d2d43&#8243;][vc_column width=&#8221;1\/2&#8243;]<div id=\"ultimate-heading-96016a57045306be8\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-96016a57045306be8 uvc-2731 \" data-hspacer=\"no_spacer\"  data-halign=\"left\" style=\"text-align:left\"><div class=\"uvc-heading-spacer no_spacer\" style=\"top\"><\/div><div class=\"uvc-main-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-96016a57045306be8 h2'  data-responsive-json-new='{\"font-size\":\"desktop:46px;mobile_landscape:34px;\",\"line-height\":\"desktop:56px;mobile_landscape:44px;\"}' ><h2 style=\"font-family:&#039;Roboto&#039;;font-weight:300;color:#ffffff;margin-bottom:30px;\">Contact info<\/h2><\/div><\/div>[vc_column_text css=&#8221;.vc_custom_1522254479777{padding-bottom: 30px !important;}&#8221;][\/vc_column_text]<div class=\"aio-icon-component  vc_custom_1705577313565   style_1\"><div id=\"Info-box-wrap-7076\" class=\"aio-icon-box default-icon\" style=\"\"  ><div class=\"aio-icon-default\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon advanced \"  style=\"color:#ffffff;background:rgba(255,255,255,0.01);border-style:solid;border-color:rgba(246,247,250,0.15);border-width:3px;width:38px;height:38px;line-height:38px;border-radius:500px;font-size:20px;display:inline-block;\">\n\t<i class=\"icomoon-free-social-contact-16x16-location\"><\/i>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-7076 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"desktop:18px;\",\"line-height\":\"desktop:18px;\"}'  style=\"color:#ffffff;\">ul. Januszowicka 5, 53-135 Wroc\u0142aw <\/h3><\/div> <!-- header --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component --><div class=\"aio-icon-component  vc_custom_1686667020337  dt-phone style_1\"><div id=\"Info-box-wrap-3634\" class=\"aio-icon-box default-icon\" style=\"\"  ><div class=\"aio-icon-default\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon advanced \"  style=\"color:#ffffff;border-style:solid;border-color:rgba(246,247,250,0.15);border-width:3px;width:38px;height:38px;line-height:38px;border-radius:500px;font-size:20px;display:inline-block;\">\n\t<i class=\"icomoon-free-social-contact-16x16-mobile\"><\/i>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-3634 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"desktop:18px;\",\"line-height\":\"desktop:18px;\"}'  style=\"color:#ffffff;\">+48 507 055 499<\/h3><\/div> <!-- header --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component --><div class=\"aio-icon-component  vc_custom_1686667036703  dt-phone style_1\"><div id=\"Info-box-wrap-5931\" class=\"aio-icon-box default-icon\" style=\"\"  ><div class=\"aio-icon-default\"><div class=\"ult-just-icon-wrapper  \"><div class=\"align-icon\" style=\"text-align:center;\">\n<div class=\"aio-icon advanced \"  style=\"color:#ffffff;border-style:solid;border-color:rgba(246,247,250,0.15);border-width:3px;width:38px;height:38px;line-height:38px;border-radius:500px;font-size:18px;display:inline-block;\">\n\t<i class=\"icomoon-free-social-contact-16x16-envelop\"><\/i>\n<\/div><\/div><\/div><\/div><div class=\"aio-icon-header\" ><h3 class=\"aio-icon-title ult-responsive\"  data-ultimate-target='#Info-box-wrap-5931 .aio-icon-title'  data-responsive-json-new='{\"font-size\":\"desktop:18px;\",\"line-height\":\"desktop:18px;\"}'  style=\"color:#ffffff;\">biuro@dise.org.pl<\/h3><\/div> <!-- header --><\/div> <!-- aio-icon-box --><\/div> <!-- aio-icon-component --><div class=\" vc_custom_1458305838876  uavc-icons \">\n<a class=\"aio-tooltip 6a570453071b8\" href=\"https:\/\/www.youtube.com\/@dise1790\/videos\" title=\"YouTube\" target=\"_blank\" rel=\"noopener\"  data-toggle=\"tooltip\" data-placement=\"\" title=\"\"><div class=\"aio-icon advanced \" data-animation=\"\" data-animation-delay=\"03\" style=\"color:#ffffff;background:#00a5ed;border-style:solid;border-color:#00a5ed;border-width:3px;width:36px;height:36px;line-height:36px;border-radius:500px;font-size:18px;margin-right:5px;\">\n\t<i class=\"icomoon-free-social-contact-16x16-youtube\"><\/i>\n<\/div><\/a>\n<a class=\"aio-tooltip 6a570453071fb\" href=\"https:\/\/www.facebook.com\/diseenergy\/\" title=\"Facebook\" target=\"_blank\" rel=\"noopener\"  data-toggle=\"tooltip\" data-placement=\"\" title=\"\"><div class=\"aio-icon advanced \" data-animation=\"\" data-animation-delay=\"03\" style=\"color:#ffffff;background:#00a5ed;border-style:solid;border-color:#00a5ed;border-width:3px;width:36px;height:36px;line-height:36px;border-radius:500px;font-size:18px;margin-right:5px;\">\n\t<i class=\"icomoon-free-social-contact-16x16-facebook\"><\/i>\n<\/div><\/a>\n<a class=\"aio-tooltip 6a57045307226\" href=\"https:\/\/twitter.com\/dise_energy\" title=\"Twitter\"  data-toggle=\"tooltip\" data-placement=\"\" title=\"\"><div class=\"aio-icon advanced \" data-animation=\"\" data-animation-delay=\"03\" style=\"color:#ffffff;background:#00a5ed;border-style:solid;border-color:#00a5ed;border-width:3px;width:36px;height:36px;line-height:36px;border-radius:500px;font-size:18px;margin-right:5px;\">\n\t<i class=\"Defaults-twitter\"><\/i>\n<\/div><\/a><\/div>[\/vc_column][vc_column width=&#8221;1\/2&#8243;]<div id=\"ultimate-heading-29736a5704530726c\" class=\"uvc-heading ult-adjust-bottom-margin ultimate-heading-29736a5704530726c uvc-3429 \" data-hspacer=\"no_spacer\"  data-halign=\"left\" style=\"text-align:left\"><div class=\"uvc-heading-spacer no_spacer\" style=\"top\"><\/div><div class=\"uvc-main-heading ult-responsive\"  data-ultimate-target='.uvc-heading.ultimate-heading-29736a5704530726c h2'  data-responsive-json-new='{\"font-size\":\"desktop:46px;mobile_landscape:34px;\",\"line-height\":\"desktop:56px;mobile_landscape:44px;\"}' ><h2 style=\"font-family:&#039;Roboto&#039;;font-weight:300;color:#ffffff;margin-bottom:30px;\">Contact form<\/h2><\/div><\/div><div class=\"wpforms-container wpforms-container-full\" id=\"wpforms-3555\"><form id=\"wpforms-form-3555\" class=\"wpforms-validate wpforms-form\" data-formid=\"3555\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/en\/wp-json\/wp\/v2\/pages\/8280\" data-token=\"bf410d266b9ce361c865b3b622fb34f7\" data-token-time=\"1784087635\"><noscript class=\"wpforms-error-noscript\">Please enable JavaScript in your browser to complete this form.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-3555-field_0-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"0\"><label class=\"wpforms-field-label\" for=\"wpforms-3555-field_0\">First name and last name: <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"text\" id=\"wpforms-3555-field_0\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][0]\" required><\/div><div id=\"wpforms-3555-field_1-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-3555-field_1\">Email <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-3555-field_1\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][1]\" spellcheck=\"false\" required><\/div><div id=\"wpforms-3555-field_2-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-3555-field_2\">Your message: <span class=\"wpforms-required-label\">*<\/span><\/label><textarea id=\"wpforms-3555-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" required><\/textarea><\/div><div id=\"wpforms-3555-field_4-container\" class=\"wpforms-field wpforms-field-checkbox\" data-field-id=\"4\"><label class=\"wpforms-field-label\" for=\"wpforms-3555-field_4\">Consent<\/label><ul id=\"wpforms-3555-field_4\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-3555-field_4_1\" name=\"wpforms[fields][4][]\" value=\"I agree to the processing of my personal data by the Lower Silesian Institute for Energy Studies, ul. Januszowicka 5, 53-135 Wroc\u0142aw for the purpose and to the extent necessary for handling this inquiry. I have read the information on how my personal data is processed in the &lt;a  href=&quot;https:\/\/dise.org.pl\/polityka-prywatnosci&quot;&gt;Information Clause&lt;\/a&gt;\"  ><label class=\"wpforms-field-label-inline\" for=\"wpforms-3555-field_4_1\">I agree to the processing of my personal data by the Lower Silesian Institute for Energy Studies, ul. Januszowicka 5, 53-135 Wroc\u0142aw for the purpose and to the extent necessary for handling this inquiry. I have read the information on how my personal data is processed in the <a href=\"https:\/\/dise.org.pl\/polityka-prywatnosci\">Information Clause<\/a><\/label><\/li><\/ul><\/div><\/div><!-- .wpforms-field-container --><div class=\"wpforms-field wpforms-field-hp\"><label for=\"wpforms-3555-field-hp\" class=\"wpforms-field-label\">Phone<\/label><input type=\"text\" name=\"wpforms[hp]\" id=\"wpforms-3555-field-hp\" class=\"wpforms-field-medium\"><\/div><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"3555\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/dise.org.pl\/en\/wp-json\/wp\/v2\/pages\/8280\">\t\t<div id=\"cf-turnstile-wpf-2384855990\"\r\n\t\tclass=\"cf-turnstile\" \t\tdata-sitekey=\"0x4AAAAAAB6rVU3c85eBv9JI\"\r\n\t\tdata-theme=\"light\"\r\n\t\tdata-language=\"auto\"\r\n\t\tdata-size=\"normal\"\r\n\t\tdata-retry=\"auto\" data-retry-interval=\"1000\"\r\n\t\tdata-action=\"wpforms-3555\"\r\n\t\t\t\tdata-appearance=\"always\"><\/div>\r\n\t\t\t<script>document.addEventListener(\"DOMContentLoaded\", function() { setTimeout(function(){ var e=document.getElementById(\"cf-turnstile-wpf-2384855990\"); e&&!e.innerHTML.trim()&&(turnstile.remove(\"#cf-turnstile-wpf-2384855990\"), turnstile.render(\"#cf-turnstile-wpf-2384855990\", {sitekey:\"0x4AAAAAAB6rVU3c85eBv9JI\"})); }, 0); });<\/script>\r\n\t\t\t<br class=\"cf-turnstile-br cf-turnstile-br-wpf-2384855990\">\r\n\t\t\t\t<style>#cf-turnstile-wpf-2384855990 { margin-left: -15px; }<\/style>\r\n\t\t<button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-3555\" class=\"wpforms-submit\" data-alt-text=\"Wysy\u0142anie\" data-submit-text=\"Send\" aria-live=\"assertive\" value=\"wpforms-submit\">Send<\/button><\/div><\/form><\/div>  <!-- .wpforms-container -->[\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space][\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row bg_type=&#8221;bg_color&#8221; bg_override=&#8221;ex-full&#8221; type=&#8221;vc_default&#8221; margin_bottom=&#8221;60&#8243; css=&#8221;.vc_custom_1521105454027{padding-top: 60px !important;padding-bottom: 60px !important;background-color: #0e182b !important;}&#8221; el_id=&#8221;kontaktwebsite&#8221; bg_color_value=&#8221;#1d2d43&#8243;][vc_column width=&#8221;1\/2&#8243;][vc_column_text css=&#8221;.vc_custom_1522254479777{padding-bottom: 30px !important;}&#8221;][\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243;][\/vc_column][\/vc_row][vc_row][vc_column][vc_empty_space][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-microsite.php","meta":[],"_links":{"self":[{"href":"https:\/\/dise.org.pl\/en\/wp-json\/wp\/v2\/pages\/8280"}],"collection":[{"href":"https:\/\/dise.org.pl\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dise.org.pl\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dise.org.pl\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/dise.org.pl\/en\/wp-json\/wp\/v2\/comments?post=8280"}],"version-history":[{"count":3,"href":"https:\/\/dise.org.pl\/en\/wp-json\/wp\/v2\/pages\/8280\/revisions"}],"predecessor-version":[{"id":8284,"href":"https:\/\/dise.org.pl\/en\/wp-json\/wp\/v2\/pages\/8280\/revisions\/8284"}],"wp:attachment":[{"href":"https:\/\/dise.org.pl\/en\/wp-json\/wp\/v2\/media?parent=8280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}